{"id":98,"date":"2018-11-12T09:33:45","date_gmt":"2018-11-12T08:33:45","guid":{"rendered":"http:\/\/historiasdelahistoria.gruporomar.nl\/?p=98"},"modified":"2022-05-02T11:05:12","modified_gmt":"2022-05-02T11:05:12","slug":"el-primer-yogur-danone","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2018\/11\/12\/el-primer-yogur-danone\/","title":{"rendered":"EL PRIMER YOGUR DANONE"},"content":{"rendered":"<p>En 1912,el gobierno de Alfonso XIII envi\u00f3 a los Balcanes al crucero acorazado Princesa de Asturias con el objetivo de repatriar a cientos de sefard\u00edes protegidos por el consulado espa\u00f1ol en Sal\u00f3nica. La que entonces era la segunda ciudad m\u00e1s importante del Imperio otomano contaba con 170.000 habitantes de los que m\u00e1s de la mitad eran jud\u00edos,en su mayor\u00eda sefard\u00edes de ascencencia espa\u00f1ola.<!--more--> Sin embargo,el nav\u00edo de la armada recal\u00f3 en Constantinopla donde aprovech\u00f3 la delegaci\u00f3n diplom\u00e1tica espa\u00f1ola en la capital turca para embarcarse en \u00e9l y regresar a Espa\u00f1a sin un solo sefard\u00ed.<\/p>\n<p>Uno de los sefard\u00edes que estaba previsto que embarcase en el Princesa de Asturias era Isaac Carasso Nehama,acomodado comerciante e importador de aceite y frutos secos de Sal\u00f3nica que pasaba por m\u00e9dico en algunos ambientes de la ciudad por sus conocimientos sobre el jaurt b\u00falgaro,yogur con propiedades medicinales que,en opini\u00f3n de cient\u00edficos de la \u00e9poca,entre ellos Ilya Metchnikoff,premio Nobel de medicina,tambi\u00e9n jud\u00edo,alargaba la vida. Carasso hab\u00eda conocido al Nobel en Par\u00eds cuando Metchnikoff era director del Instituto Pasteur.<\/p>\n<p>Carasso hab\u00eda descubierto las propiedades del jaurt en sus viajes a regiones aisladas del norte de Bulgaria. Las crueles guerras balc\u00e1nicas (antes,la guerra italo-turca) le aconsejaron dejar su tierra adoptiva,Sal\u00f3nica,y regresar a su tierra natal,Sefarad (Espa\u00f1a) y de ah\u00ed su inter\u00e9s por embarcarse en el acorazado espa\u00f1ol. Como no pudo ser,abandon\u00f3 Sal\u00f3nica d\u00edas despu\u00e9s del asesinato,en el Paseo Mar\u00edtimo de la ciudad,del Rey Jorge de Grecia,que d\u00edas antes hab\u00eda entrado triunfante,montado a caballo,con su ej\u00e9rcito. Sal\u00f3nica volv\u00eda a ser griega,pero los sefard\u00edes tem\u00edan que los nuevos due\u00f1os de la ciudad les privaran de sus privilegios.<\/p>\n<p>Isaac Carasso,con su mujer,Esther,y sus hijos Daniel,Flor y Juana,inici\u00f3 un largo viaje por ferrocarril. La I Guerra Mundial le sorprendi\u00f3 en Suiza,que hab\u00eda movilizado un ej\u00e9rcito de 200.000 hombres,bien pertrechados,para defender su neutralidad. En Lausana,inici\u00f3,en plan experimental,la producci\u00f3n del jaurt que le ense\u00f1aron a elaborar los pastores b\u00falgaros. Pero,convencido de que el final de su viaje deb\u00eda ser Espa\u00f1a,no dud\u00f3 en cruzar Francia,a pesar de la guerra,y llegar a Barcelona,donde se aloj\u00f3 con su familia en un piso del Raval (concretamente,en el Carrer dels \u00c0ngels). All\u00ed,en una habitaci\u00f3n,instal\u00f3 un laboratorio artesanal donde vio la luz el primer Danone del mundo. Carasso se las arregl\u00f3 para que los m\u00e9dicos respaldaran su producto,que \u00e9l consideraba un \u00abelixir de la eternidad\u00bb. Quien m\u00e1s le ayud\u00f3 fue el investigador Ferran y Cl\u00faa,a quien en Europa denominaban \u00abel Pasteur espa\u00f1ol\u00bb. As\u00ed empez\u00f3 a distribuir su producto,en art\u00edsticos envases de porcelana,en las farmacias de Barcelona,gracias a la ayuda que le prestaron los carteros de la ciudad.<\/p>\n<p>As\u00ed,en 1919,empez\u00f3 la aventura del yogur Danone (cuyo nombre fue inspirado por su hijo Daniel).<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-988 aligncenter\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/danone.jpg\" alt=\"\" width=\"346\" height=\"487\" \/><\/p>\n<p style=\"text-align: center;\">En la foto Isaac Carasso junto a su sobrino Mario Botton,degustando el invento en la azotea de su casa en el Carrer dels \u00c0ngels.<\/p>\n<p>FUENTE: J.Pardo(ampliaci\u00f3n Internet).<\/p>\n<p>Foto:Internet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1912,el gobierno de Alfonso XIII envi\u00f3 a los Balcanes al crucero acorazado Princesa de Asturias con el objetivo de repatriar a cientos de sefard\u00edes protegidos por el consulado espa\u00f1ol en Sal\u00f3nica. La que entonces era la segunda ciudad m\u00e1s importante del Imperio otomano contaba con 170.000 habitantes de los que m\u00e1s de la mitad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-98","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/98\/revisions"}],"predecessor-version":[{"id":1251,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/98\/revisions\/1251"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=98"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=98"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}