{"id":777,"date":"2020-11-16T08:42:41","date_gmt":"2020-11-16T08:42:41","guid":{"rendered":"http:\/\/historiasdelahistoria.rodmar.es\/?p=777"},"modified":"2020-11-16T08:42:47","modified_gmt":"2020-11-16T08:42:47","slug":"la-capilla-de-marcus","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2020\/11\/16\/la-capilla-de-marcus\/","title":{"rendered":"LA CAPILLA DE MARC\u00daS"},"content":{"rendered":"\n<p>En el cruce de las calles Carders y Montcada,encontramos la capilla de Marc\u00fas,un lugar emblem\u00e1tico y a la vez,desconocido de Barcelona,a causa de un horario restrictivo en lo que se refiere al acceso al interior y,especialmente,a la cripta. Aunque el interior de la capilla exhibe una decoraci\u00f3n neocl\u00e1sica,este peque\u00f1o templo se remonta a la segunda mitad del siglo XII,cuando Bernat Marc\u00fas,un rico burgu\u00e9s de la \u00e9poca,financi\u00f3 la construcci\u00f3n,junto con la de un hospital,un cementerio para pobres y un albergue para viajeros.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Desde hace un tiempo,la capilla de Marc\u00fas es un poco m\u00e1s conocida gracias a Antonio Aguilar,un funcionario de Correos que organiza una ruta muy interesante por la historia del servicio postal en Barcelona. La capilla es uno de los atractivos del itinerario,ya que en la Edad Media fue la sede de la cofrad\u00eda de los correos.<\/p>\n\n\n\n<p>La capilla se construy\u00f3 en su d\u00eda fuera de la antigua muralla romana y es uno de los escasos vestigios de arquitectura rom\u00e1nica que quedan en Barcelona. Situada cerca del monasterio de St. Pere de les Puel\u00b7les,de la entrada oriental de la ciudad (lo que hoy es la plaza del \u00c1ngel) y de la bifurcaci\u00f3n de diversos caminos importantes,su situaci\u00f3n (junto con la del hospital y el albergue) era estrat\u00e9gica para la acogida de peregrinos. A\u00f1os despu\u00e9s,alrededor de este conjunto creci\u00f3 el n\u00facleo urbano de St. Pere,ya en el interior de la muralla medieval.<\/p>\n\n\n\n<p>Dentro de la capilla,todo y las m\u00faltiples transformaciones,todav\u00eda es visible la b\u00f3veda de ca\u00f1\u00f3n que distingue al estilo rom\u00e1nico. Conserva,tambi\u00e9n,unas gradas laterales. Pero la joya del templo es,sin duda,la cripta subterr\u00e1nea,a la cual se accede por una escalera estrecha,oculta tras una puerta al lado del altar. Se trata de una estructura con forma de cruz latina que presumiblemente se construy\u00f3 durante el siglo XVII para poder ampliar el aforo para los servicios religiosos. Bajar a la cripta es una experiencia al alcance de unos pocos actualmente,lo cual,a la pr\u00e1ctica,la convierte casi en un secreto.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/10\/IMG_20201006_180419.jpg\" alt=\"\" class=\"wp-image-779\" width=\"375\" height=\"376\" srcset=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/10\/IMG_20201006_180419.jpg 422w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/10\/IMG_20201006_180419-300x300.jpg 300w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/10\/IMG_20201006_180419-150x150.jpg 150w\" sizes=\"(max-width: 375px) 100vw, 375px\" \/><figcaption>CAPILLA DE MARC\u00daS<\/figcaption><\/figure><\/div>\n\n\n\n<p>En el siglo XIV fue la sede de la cofrad\u00eda de los correos de Barcelona,la primera organizaci\u00f3n del oficio postal de Europa. Era aqu\u00ed donde los correos a caballo y a pie recib\u00edan la bendici\u00f3n antes de partir. En la capilla se venera,desde finales del siglo XVIII,una imagen de la Mare de D\u00e9u de la Gu\u00eda,que los correos adoptaron como patrona despu\u00e9s que fuese trasladada desde otro templo ya desaparecido que se encontraba al lado del Portal Nou de la muralla medieval,cerca de donde hoy se levanta el Arco de Triunfo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el cruce de las calles Carders y Montcada,encontramos la capilla de Marc\u00fas,un lugar emblem\u00e1tico y a la vez,desconocido de Barcelona,a causa de un horario restrictivo en lo que se refiere al acceso al interior y,especialmente,a la cripta. Aunque el interior de la capilla exhibe una decoraci\u00f3n neocl\u00e1sica,este peque\u00f1o templo se remonta a la segunda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-777","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=777"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/777\/revisions"}],"predecessor-version":[{"id":780,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/777\/revisions\/780"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}