{"id":714,"date":"2020-09-23T12:52:14","date_gmt":"2020-09-23T12:52:14","guid":{"rendered":"http:\/\/historiasdelahistoria.rodmar.es\/?p=714"},"modified":"2020-09-23T12:52:16","modified_gmt":"2020-09-23T12:52:16","slug":"y-entonces-llego-almanzor","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2020\/09\/23\/y-entonces-llego-almanzor\/","title":{"rendered":"Y ENTONCES LLEG\u00d3 ALMANZOR"},"content":{"rendered":"\n<p>Para muchos es conocido el dicho: \u00abEn Calata\u00f1azor,Almanzor perdi\u00f3 el tambor\u00bb,para as\u00ed recordar la derrota infligida por las huestes cristianas al caudillo musulm\u00e1n. Pero a veces,la leyenda tiene sus problemas: as\u00ed,no son pocos los medievalistas que ahora insisten en que tal enfrentamiento no existi\u00f3 y que no fue m\u00e1s que propaganda para desprestigiar a un militar invencible. Ahora bien,lo que es indudable es que Almanzor se plant\u00f3 ante las murallas de Barcelona en el a\u00f1o 985 y que someti\u00f3 a la ciudad a una de las peores destrucciones de su historia.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Joan Roca,director del Museu d&#8217;Historia de Barcelona,sostiene que la ciudad ha pasado por tres grandes traumas. Los bombardeos de la Guerra Civil y el sitio de 1714 son dos,y la destrucci\u00f3n de la urbe por parte de Almanzor,el primero. Curiosamente,sobre un episodio tan notable pr\u00e1cticamente no hay pruebas arqueol\u00f3gicas: en ning\u00fan sitio se han encontrado sustratos que certifiquen el asedio ni los incendios que entonces debieron tener lugar,pero sabemos que ocurri\u00f3 por la documentaci\u00f3n que hay sobre este episodio.<\/p>\n\n\n\n<p>Almanzor,caudillo militar que atorment\u00f3 a los reinos cristianos en el siglo X,naci\u00f3 en Algeciras en el a\u00f1o 939,sirvi\u00f3 al califato de C\u00f3rdoba y en sus correr\u00edas cruz\u00f3 la Pen\u00ednsula,hasta Santiago de Compostela. Curiosamente,aunque varias de sus razzias est\u00e1n profusamente documentadas,sobre su incursi\u00f3n a Barcelona las fuentes no son abundantes. Del lado cristiano,est\u00e1 la Cr\u00f3nica del monasterio de Sant Pere de les Puel\u00b7les,posterior a los acontecimientos,y presenta serias dudas. Tampoco hay profusi\u00f3n de relatos \u00e1rabes. Pero en libros,art\u00edculos y tesis doctorales hay puntos comunes. Uno de ellos es que esper\u00f3 para asaltar la ciudad a que los condes de Barcelona se hubieran desligado definitivamente de los reyes francos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/09\/almanzor.jpg\" alt=\"\" class=\"wp-image-715\" srcset=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/09\/almanzor.jpg 800w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/09\/almanzor-300x225.jpg 300w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2020\/09\/almanzor-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>BUSTO DE ALMANZOR EN CALATA\u00d1AZOR<\/figcaption><\/figure>\n\n\n\n<p>Almanzor sali\u00f3 de C\u00f3rdoba el 5 de mayo de 985 y emprendi\u00f3 el camino hacia Barcelona por la costa mediterr\u00e1nea. Tambi\u00e9n sabemos que el asalto fue precedido de una batalla en la que el conde Borrell II intent\u00f3 evitar lo que se avecinaba. Hay grandes discrepancias sobre d\u00f3nde y cu\u00e1ndo se produjo este enfrentamiento,pero lo que es seguro es que los cristianos fueron derrotados. Lo que no es cierto es que Borrell II perdiera la vida en la lid,pues est\u00e1 comprobado que vivi\u00f3 a\u00fan a\u00f1os.<\/p>\n\n\n\n<p>Las fuentes \u00e1rabes y cristianas coinciden en se\u00f1alar que Almanzor se plant\u00f3 ante los muros de Barcelona el 1 de julio de 985 e iniciaron un cerco imposible de resistir para los barceloneses. Una de las causas de la superioridad del ej\u00e9rcito \u00e1rabe es que los jinetes hab\u00edan recubierto sus brazos con l\u00e1minas de acero,que les permit\u00eda defenderse de los golpes de las espadas creadas por los francos. Tambi\u00e9n hay narraciones acerca de episodios macabros,como que los sitiadores lanzaban las cabezas de los caballeros abatidos en la batalla anterior al interior del per\u00edmetro,para acobardar a los defensores. El d\u00eda 6,Almanzor tom\u00f3 la ciudad a sangre y fuego.<\/p>\n\n\n\n<p>Como queda dicho,no hay restos arqueol\u00f3gicos de los incendios y saqueos que,a buen seguro tuvieron que ocurrir,pero tenemos noticias de la hecatombe por otra v\u00eda: una de las consecuencias de la conquista fue la toma de cautivos,cuyos rescates est\u00e1n documentados. Hay autores que apuntan a escenas dantescas,como una suerte de mercado celebrado en las inmediaciones de la urbe adonde acudieron los familiares para saber qu\u00e9 suerte correr\u00edan sus deudos,ya prisioneros. Hay constancia de rehenes en C\u00f3rdoba y Huesca.<\/p>\n\n\n\n<p>Los documentos de los rescates nos han legado los nombres de algunos de estos prisioneros. Por ejemplo,Emma,esposa de Guillem,que luch\u00f3 en defensa de la ciudad. O Udalard,hijo del vizconde Guitard. O el juez Aur\u00fas,que ya estaba de vuelta en Barcelona en el 986,tras pagar su rescate,para lo cual goz\u00f3 de una ayuda del monasterio de Sant Cugat que no fue desinteresada,pues le exigieron parte de su patrimonio.<\/p>\n\n\n\n<p>Y,as\u00ed es la condici\u00f3n humana,el regreso no fue f\u00e1cil ni alegre para todos. El 8 de mayo del a\u00f1o 1000 se celebr\u00f3 un juicio en el palacio real. La causa es que una mujer llamada Madrona denunci\u00f3 que mientras permaneci\u00f3 recluida en C\u00f3rdoba,su hermano Bonhome le hab\u00eda usurpado sus bienes y los de su difunto marido,Enneg\u00f3. Comprobada la veracidad de la acusaci\u00f3n,este descendiente de Ca\u00edn fue obligado a retornar las vi\u00f1as y tierras de sus parientes,ubicadas en la zona de Mag\u00f2ria.<\/p>\n\n\n\n<p>Las fuentes \u00e1rabes sit\u00faan a Almanzor de regreso a C\u00f3rdoba el 23 de julio. O sea,que se entretuvo poco en su correr\u00eda,cuya consecuencia fue la devastaci\u00f3n de Barcelona. Muri\u00f3 el 9 de agosto de 1002 en Medinacelli,de enfermedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para muchos es conocido el dicho: \u00abEn Calata\u00f1azor,Almanzor perdi\u00f3 el tambor\u00bb,para as\u00ed recordar la derrota infligida por las huestes cristianas al caudillo musulm\u00e1n. Pero a veces,la leyenda tiene sus problemas: as\u00ed,no son pocos los medievalistas que ahora insisten en que tal enfrentamiento no existi\u00f3 y que no fue m\u00e1s que propaganda para desprestigiar a un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-714","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=714"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/714\/revisions"}],"predecessor-version":[{"id":717,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/714\/revisions\/717"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}