{"id":577,"date":"2020-03-10T18:59:07","date_gmt":"2020-03-10T17:59:07","guid":{"rendered":"http:\/\/historiasdelahistoria.gruporomar.nl\/?p=577"},"modified":"2022-05-02T16:29:34","modified_gmt":"2022-05-02T16:29:34","slug":"el-cagalell","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2020\/03\/10\/el-cagalell\/","title":{"rendered":"EL CAGALELL."},"content":{"rendered":"\n<p>El Cagalell era una zona de albuferas de la cual se tiene constancia de su existencia por mapas de la ciudad hasta el siglo XIII,y que ocupar\u00eda el tri\u00e1ngulo que formar\u00edan en la actualidad la Av. del Paral.lel,Las Ramblas y la calle de St. Pau. Es decir,el actual barrio del Raval,anteriormente llamado peyorativamente Barrio Chino.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Esta zona de marismas quedaba en el exterior de las murallas de Barcelona y recib\u00eda la escorrent\u00eda de diversas rieras y torrentes que bajaban desde Collserola,tales como la Riera de Valldonzella,la de Magoria,la de la Creu d&#8217;En Malla y,posteriormente,se hizo desembocar la Riera de Collserola (la actual Rambla).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"610\" height=\"407\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/15838591661786770447385438864509.png\" alt=\"\" class=\"wp-image-932\"\/><figcaption>BARCELONA HACE 10.000 A\u00d1OS<\/figcaption><\/figure><\/div>\n\n\n\n<p>El origen de esta zona de albufera se encuentra en el final de la \u00faltima glaciaci\u00f3n,cuando la subida del nivel del mar dej\u00f3 una peque\u00f1a bah\u00eda entre la monta\u00f1a de Montjuic y la peque\u00f1a colina del monte Taber,situada donde hoy se encuentra la Pl. St. Jaume. Con el tiempo,las corrientes de norte a sur que circulan por la costa barcelonesa,cerraron esta peque\u00f1a bah\u00eda con una barrera de arena (m\u00e1s o menos ubicada a la altura del actual monumento a Col\u00f3n) dejando tras de si una zona de lagunas litorales.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/15838592461923880499430715389369.png\" alt=\"\" class=\"wp-image-933\" width=\"508\" height=\"334\"\/><figcaption>EL CAGALELL EN EL SIGLO XIII<\/figcaption><\/figure><\/div>\n\n\n\n<p>Aquella laguna,con el desarrollo de Barcino,empez\u00f3 a recibir las aguas residuales de la ciudad que bajaban por los diversos torrentes que la atravesaban. Si las zonas de marismas ya eran de por si zonas insanas,fuente de infinidad de enfermedades,el hecho de recibir todas las \u00abmiserias\u00bb humanas,lo convert\u00eda en un aut\u00e9ntico estercolero,lo que llev\u00f3 a la poblaci\u00f3n a bautizarlo como \u00abCagalell\u00bb.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"506\" height=\"304\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/15838592814306780578768476578468-2.png\" alt=\"\" class=\"wp-image-934\"\/><figcaption>SITUACI\u00d3N DEL CAGALELL.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Con el crecimiento de la ciudad,las tan insalubres lagunas quedaron a un paso de las murallas y,una parte por el aporte sedimentario de las rieras y otra por el aporte humano,las marismas se colmataron,permitiendo su urbanizaci\u00f3n durante los siglos XIV y XV,desapareciendo de las cartograf\u00edas de la ciudad a partir del siglo XVI.<\/p>\n\n\n\n<p>Hoy en d\u00eda,la zona del Cagalell es una zona que da especiales quebraderos de cabeza a los arquitectos a la hora de construir,ya que entre los 5 y los 15 metros hay una capa de arcillas y limos grises con mucha materia org\u00e1nica,que produce problemas en la cimentaci\u00f3n de las edificaciones y que corresponden a restos de aquella albufera litoral hoy desaparecida.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/15838593154815289865466086810304-2.png\" alt=\"\" class=\"wp-image-935\" width=\"563\" height=\"418\"\/><figcaption>SEDIMENTOS DEL CAGALELL<\/figcaption><\/figure><\/div>\n\n\n\n<p>La ciudad ha modificado totalmente su entorno natural primigenio,pero el hecho de que no seamos capaces de imaginarlo viendo el actual trazado urbano,no significa que no haya existido,y merece la pena recordar que bajo nuestros pies un mundo vivo nos aguanta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cagalell era una zona de albuferas de la cual se tiene constancia de su existencia por mapas de la ciudad hasta el siglo XIII,y que ocupar\u00eda el tri\u00e1ngulo que formar\u00edan en la actualidad la Av. del Paral.lel,Las Ramblas y la calle de St. Pau. Es decir,el actual barrio del Raval,anteriormente llamado peyorativamente Barrio Chino.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-577","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=577"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/577\/revisions"}],"predecessor-version":[{"id":1287,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/577\/revisions\/1287"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}