{"id":536,"date":"2020-03-19T19:00:57","date_gmt":"2020-03-19T18:00:57","guid":{"rendered":"http:\/\/historiasdelahistoria.gruporomar.nl\/?p=536"},"modified":"2022-05-02T16:21:25","modified_gmt":"2022-05-02T16:21:25","slug":"la-calle-de-la-duda","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2020\/03\/19\/la-calle-de-la-duda\/","title":{"rendered":"LA CALLE DE LA DUDA"},"content":{"rendered":"\n<p>Al comienzo de la calle Riera Alta,entrando desde la ronda St. Antoni,se abre un peque\u00f1o espacio p\u00fablico donde el fil\u00f3sofo Ren\u00e9 Descartes habr\u00eda estado encantado de residir. Porque Descartes,que hizo de la duda su m\u00e9todo filos\u00f3fico,lleg\u00f3 a la conclusi\u00f3n que exist\u00eda porque dudaba. De aqu\u00ed viene su c\u00e9lebre sentencia \u00abpienso,luego existo\u00bb.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Y es que la placita se llama precisamente del Dubte,tal y como consta en la placa del nomenclator. Es curioso que,justo debajo,sobrevive otra placa m\u00e1s antigua con la inscripci\u00f3n de \u00abcalle de La Duda\u00bb. Lo que aparentemente es una contradicci\u00f3n deja de serlo cuando se escarba un poco en la historia del lugar o cuando se recuerda perfectamente que se encontraba all\u00ed antes de ser una plaza.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/IMG_20200128_130918-2.jpg\" alt=\"\" class=\"wp-image-1086\" width=\"558\" height=\"743\"\/><figcaption>CALLE DE LA DUDA. PLA\u00c7A DEL DUBTE.<br>FOTO: GLORIX<\/figcaption><\/figure><\/div>\n\n\n\n<p>La calle de La Duda era la m\u00e1s corta de la ciudad. Ten\u00eda 12 metros de largo y compet\u00eda directamente con la calle Anisadeta,al lado de Sta. M. del Mar. Era un peque\u00f1o carrer\u00f3n que separaba dos edificios,el que todav\u00eda hace esquina en la plaza con las calles Pr\u00edncep de Viana,Cendra y otro que ya ha desaparecido. La demolici\u00f3n de esta calle,en el a\u00f1o 1995,es lo que dio origen a la plaza actual.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/IMG_20200128_130944.jpg\" alt=\"\" class=\"wp-image-1087\" width=\"518\" height=\"691\"\/><figcaption>PL. DEL DUBTE. AL FONDO LA PARTE SUPERVIVIENTE DE LA CALLE DE LA DUDA.<br>FOTO: GLORIX<\/figcaption><\/figure><\/div>\n\n\n\n<p>La calle de La Duda,seg\u00fan los testimonios que han llegado hasta nuestros d\u00edas,no ten\u00eda nada especial excepto una fuente de dos bocas. Y es este doble surtidor el que,seg\u00fan el folklorista Joan Amades,dio origen a un nombre tan original. Parece que la denominaci\u00f3n se remonta a una antigua disputa entre tres campesinos. Cada uno afirmaba que el agua de la fuente proced\u00eda de sus tierras. Siempre seg\u00fan Amades,como que este punto no se pudo comprobar con seguridad,qued\u00f3 la duda,de manera que primero la fuente y m\u00e1s tarde la calle fueron bautizadas as\u00ed.<\/p>\n\n\n\n<p>La calle y la fuente desaparecieron con el derribo de la finca que ocupaba la plaza actual,todo y que se ha conservado,como en otros casos,la antigua placa que indica que formaba parte del \u00abdistrito 3\u00bb y del \u00abbarrio 2\u00bb. Por lo que parece,una casa de citas conocida como  \u00abEl R\u00e1pido\u00bb desarrollaba su actividad en el edificio. Los amantes furtivos entraban por la calle Pr\u00edncep de Viana y sal\u00edan por una puerta estrecha al lado de la fuente.<\/p>\n\n\n\n<p>La obertura de la plaza ha permitido que se haya rehabilitado el acceso al edificio para una actividad comercial en la fachada superviviente de la calle de La Duda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al comienzo de la calle Riera Alta,entrando desde la ronda St. Antoni,se abre un peque\u00f1o espacio p\u00fablico donde el fil\u00f3sofo Ren\u00e9 Descartes habr\u00eda estado encantado de residir. Porque Descartes,que hizo de la duda su m\u00e9todo filos\u00f3fico,lleg\u00f3 a la conclusi\u00f3n que exist\u00eda porque dudaba. De aqu\u00ed viene su c\u00e9lebre sentencia \u00abpienso,luego existo\u00bb.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-536","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=536"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/536\/revisions"}],"predecessor-version":[{"id":1283,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/536\/revisions\/1283"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}