{"id":533,"date":"2020-01-28T18:52:58","date_gmt":"2020-01-28T17:52:58","guid":{"rendered":"http:\/\/historiasdelahistoria.gruporomar.nl\/?p=533"},"modified":"2022-05-02T16:45:44","modified_gmt":"2022-05-02T16:45:44","slug":"el-elefante-de-la-catedral","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2020\/01\/28\/el-elefante-de-la-catedral\/","title":{"rendered":"EL ELEFANTE DE LA CATEDRAL"},"content":{"rendered":"\n<p>La catedral de Barcelona es fuente inagotable de leyendas. Una de \u00e9stas tiene como protagonista una de las 160 g\u00e1rgolas del templo,la que representa un elefante con una especie de construcci\u00f3n en forma de torre o palanqu\u00edn en el lomo. Dice la leyenda que,si se le rompiese la trompa,el mundo se hundir\u00eda. A\u00f1ado que se ha roto en un par de ocasiones y el mundo,aparentemente,todav\u00eda sigue como si nada.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>La g\u00e1rgola del elefante se encuentra en el \u00e1bside,situada hacia el Palau del Lloctinent. Se restaur\u00f3 en 1997,junto con otras g\u00e1rgolas. El elefante recuper\u00f3 su trompa y se reconstruy\u00f3 el palanqu\u00edn,que estaba muy deteriorado. Tanto \u00e9sta como sus vecinas,que representan un unicornio y un toro,son sin duda las tres g\u00e1rgolas m\u00e1s singulares de toda la catedral.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/IMG_20200128_133830.jpg\" alt=\"\" class=\"wp-image-1088\" width=\"360\" height=\"476\"\/><figcaption>G\u00c1RGOLA DEL ELEFANTE. CATEDRAL DE BARCELONA.<br>FOTO: GLORIX<\/figcaption><\/figure><\/div>\n\n\n\n<p>Durante la d\u00e9cada de 1960,la g\u00e1rgola del elefante protagoniz\u00f3 un incidente que incluso tuvo repercusi\u00f3n en la prensa de la \u00e9poca. Como que la trompa estaba da\u00f1ada,los d\u00edas de lluvia el agua ca\u00eda directamente sobre la capilla del Sagrado Coraz\u00f3n,y \u00e9sto provocaba filtraciones y humedades. Entonces se instal\u00f3 un tubo que la prolongaba,de manera que el agua iba directamente a parar a la fachada del Palau del Lloctinent,lo que provoc\u00f3 las quejas de los responsables del Arxiu de la Corona d&#8217;Arag\u00f3. Finalmente,se procedi\u00f3 a la impermeabilizaci\u00f3n del tejado de la capilla y se resolvi\u00f3 el problema.<\/p>\n\n\n\n<p>La raz\u00f3n por la cual una de las g\u00e1rgolas de la catedral representa un elefante sigue siendo un misterio sin resolver. Este tipo de canalizaciones se empezaron a instalar en las iglesias g\u00f3ticas en el siglo XIII. Al principio ten\u00edan un objetivo pr\u00e1ctico: alejar de los muros el agua de la lluvia. Pero r\u00e1pidamente se aprovecharon tambi\u00e9n como recurso decorativo,con motivos inspirados en la mitolog\u00eda cristiana. No obstante,el elefante no era un animal demasiado conocido en la Europa de la Edad Media. De hecho,m\u00e1s bien forma parte de la tradici\u00f3n oriental,y concretamente de la simbolog\u00eda hind\u00fa,como elemento que sostiene el cosmos.<\/p>\n\n\n\n<p>Pero el elefante con palanqu\u00edn en el lomo tambi\u00e9n es una m\u00e1quina de guerra de la antig\u00fcedad. An\u00edbal utiliz\u00f3 elefantes con esta finalidad,y en la Biblia se relata que Judas Macabeo se enfrent\u00f3 a ellos en su lucha con los persas. A pesar de \u00e9sto,es dif\u00edcil pensar que la g\u00e1rgola de la catedral de Barcelona pueda hacer referencia a este episodio b\u00edblico. Lo m\u00e1s acertado es suponer,como apuntan algunos estudiosos,que representa una especie de fortaleza de la Iglesia.<\/p>\n\n\n\n<p> Sea como sea,vale la pena buscarla y admirar la originalidad de esta g\u00e1rgola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La catedral de Barcelona es fuente inagotable de leyendas. Una de \u00e9stas tiene como protagonista una de las 160 g\u00e1rgolas del templo,la que representa un elefante con una especie de construcci\u00f3n en forma de torre o palanqu\u00edn en el lomo. Dice la leyenda que,si se le rompiese la trompa,el mundo se hundir\u00eda. A\u00f1ado que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-533","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=533"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/533\/revisions"}],"predecessor-version":[{"id":1297,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/533\/revisions\/1297"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}