{"id":49,"date":"2018-10-17T20:44:18","date_gmt":"2018-10-17T18:44:18","guid":{"rendered":"http:\/\/historiasdelahistoria.gruporomar.nl\/?p=49"},"modified":"2022-05-02T10:28:04","modified_gmt":"2022-05-02T10:28:04","slug":"origenes-ii","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2018\/10\/17\/origenes-ii\/","title":{"rendered":"OR\u00cdGENES II"},"content":{"rendered":"<p>En la suave cima del monte T\u00e1ber de casi 17 metros de desnivel (lo que hoy en d\u00eda es Pl. St. Jaume) se sit\u00faa el epicentro de Barcino y su foro. Su cumbre est\u00e1 se\u00f1alada en la calle Parad\u00eds,en el suelo,justo delante de la entrada de la sede del Centro excursionista de Catalu\u00f1a. Dentro de este edificio,encajadas en un patio de luces,se encuentran las columnas del templo de Augusto.<\/p>\n<p><!--more-->Se considera que la fundaci\u00f3n de Barcino por el emperador Augusto fue alrededor del a\u00f1o 10 a. C.(quince a\u00f1os antes ya se hab\u00eda fundado B\u00e9tulo al otro lado del Bes\u00f3s). Fue una ciudad peque\u00f1a,de unas 10 hect\u00e1reas,cerrada por una muralla. Su planta irregular,formando un rect\u00e1ngulo con los \u00e1ngulos cortados,se debi\u00f3 simplemente a la necesidad de adaptarse a la topograf\u00eda del terreno. La ciudad quedaba mucho m\u00e1s cerca del mar que ahora,desde la Puerta del Mar hasta el Mare Nostrum hab\u00edan unos escasos 150 metros. Fuera de las murallas,en el \u00absuburbium\u00bb,se encontraban los espacios de producci\u00f3n,como talleres de cer\u00e1mica,metalurgia y tambi\u00e9n estructuras de h\u00e1bitat,como las \u00abvillae\u00bb y las \u00abdomus suburbanas\u00bb. A ambos lados de la Puerta del Mar hab\u00edan dos conjuntos termales destinados,seguramente,a hombres y mujeres por separado.<\/p>\n<p>El m\u00e1ximo esplendor de Barcino se dio durante el siglo II d. C.,con el m\u00e1ximo de poblaci\u00f3n censada. Un personaje que destac\u00f3 sobre todos los dem\u00e1s en esta \u00e9poca fue Lucio Minicio Natal Quadroni Ver,quien junto a su padre mand\u00f3 construir las termas de la ciudad.<\/p>\n<p>Se form\u00f3 un sistema de gobierno,se crearon templos,acueductos y termas.<\/p>\n<p>Por el valor de los restos arqueol\u00f3gicos(tama\u00f1o del templo,abundancia de esculturas,mosaicos,\u00e1nforas,etc)se ha podido deducir que los habitantes gozaron de un buen nivel de vida. Por tanto,es imaginable la importancia que lleg\u00f3 a tener esta peque\u00f1a ciudad.<\/p>\n<p>Se atribuye,por decirlo de alguna manera,la colocaci\u00f3n de la primera piedra de Barcino a Lucius Licinius Secundus,servir augustal de Tarraco(Colonia Iulia Urbs Triumphalis Tarraco),de Barcino y de B\u00e9tulo.<\/p>\n<p>Durante siglos se ha hablado de Barcino como una simple colonia romana que pas\u00f3 sin pena ni gloria. Desde hace ya unos a\u00f1os y gracias a la creaci\u00f3n del Pla Barcino,se han podido acumular muchos m\u00e1s datos y conocimientos sobre Barcino y se han empezado a replantear algunas cosas.<\/p>\n<p>Se debate sobre el templo y el foro. Se duda de la exactitud de los planos de Barcino. Complicado intervenir y excavar,el epicentro de la ciudad romana estar\u00eda a varios metros bajo la Pl. St. Jaume. Actualmente y dentro del Pla Barcino est\u00e1n previstas una serie de intervenciones con georadares y excavaciones controladas,aunque todav\u00eda no tienen fecha de inicio.<\/p>\n<p>Desde su fundaci\u00f3n,hab\u00edan barrios planificados fuera de las murallas y un suburbio portuario potente. Se descarta el acueducto de Collserola(las aguas que entraban en Barcino a trav\u00e9s de sus dos acueductos proven\u00edan de fuentes cercanas al Bes\u00f3s).<\/p>\n<p>Se empieza a redescubrir el papel clave del \u00e1rea de Sants Just i Pastor,se descubre el desmesurado tama\u00f1o de las viviendas y equipamientos del interior de las murallas,la extensa y lujos\u00edsima villa de La Sagrera. Sin viviendas humildes dentro de las murallas,con tres termas p\u00fablicas y termas privadas en muchas \u00abdomus\u00bb. Una ciudad muy peque\u00f1a en metros cuadrados pero muy potente,que nace para controlar el territorio,lo que viene del interior,del mar y la producci\u00f3n de vino;una ciudad de ricos. Un territorio que llegar\u00eda hasta los asentamientos agrarios del Llobregat y el Bes\u00f3s.<\/p>\n<p>Y como los grandes enigmas traen sus propias leyendas,existen ciertas hip\u00f3tesis sobre un anfiteatro todav\u00eda no localizado bajo la bas\u00edlica de Sta. Mar\u00eda del Mar. Tambi\u00e9n forma parte del Pla Barcino intentar localizar restos que ya no dejen ninguna duda sobre la existencia del anfiteatro de Barcino.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-967 aligncenter\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/barcinoromana-3.jpg\" alt=\"\" width=\"455\" height=\"436\" \/><\/p>\n<p style=\"text-align: center;\">FOTOGRAF\u00cdA: Internet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la suave cima del monte T\u00e1ber de casi 17 metros de desnivel (lo que hoy en d\u00eda es Pl. St. Jaume) se sit\u00faa el epicentro de Barcino y su foro. Su cumbre est\u00e1 se\u00f1alada en la calle Parad\u00eds,en el suelo,justo delante de la entrada de la sede del Centro excursionista de Catalu\u00f1a. Dentro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-49","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/49\/revisions"}],"predecessor-version":[{"id":1227,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/49\/revisions\/1227"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=49"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=49"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}