{"id":453,"date":"2019-11-23T13:24:55","date_gmt":"2019-11-23T12:24:55","guid":{"rendered":"http:\/\/historiasdelahistoria.gruporomar.nl\/?p=453"},"modified":"2022-05-02T17:42:57","modified_gmt":"2022-05-02T17:42:57","slug":"el-santuario-de-la-cirugia","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2019\/11\/23\/el-santuario-de-la-cirugia\/","title":{"rendered":"EL SANTUARIO DE LA CIRUG\u00cdA"},"content":{"rendered":"\n<p>El recinto del antiguo Hospital de la Santa Creu,en el Raval,guarda uno de los vestigios relacionados con la pr\u00e1ctica de la medicina en el siglo XVIII m\u00e1s desconocido y valioso,casi \u00fanico en Europa. Se trata del anfiteatro anat\u00f3mico construido en 1762 en la vieja sede del Colegio de Cirug\u00eda y que hoy alberga la Academia de Medicina. El conjunto se puede visitar en horas concertadas. Cuando uno lo contempla no puede evitar evocar el lienzo de Rembrandt \u00abLa lecci\u00f3n de anatom\u00eda del Dr. Nicolaes Tulp\u00bb.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>La pieza central del anfiteatro,donde los ojos se dirigen casi de manera hipn\u00f3tica,es la mesa de disecci\u00f3n de m\u00e1rmol,una de las pocas que se conservan,en la cual el agujero central por donde se evacuaban los l\u00edquidos todav\u00eda es perfectamente visible. A su alrededor se disponen una serie de asientos de madera y unas gradas de piedra desde donde se pod\u00edan observar las intervenciones.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/img-20181103-wa0043.jpg\" alt=\"\" class=\"wp-image-1132\" width=\"496\" height=\"373\"\/><figcaption>ANFITEATRO ANAT\u00d3MICO DEL SIGLO XVIII.<br>BARCELONA<br><\/figcaption><\/figure><\/div>\n\n\n\n<p>La sala es circular,cubierta por una c\u00fapula esf\u00e9rica donde est\u00e1n representados algunos de los protagonistas m\u00e1s ilustres de la medicina en Catalu\u00f1a,y est\u00e1 coronada por un reflector. El edificio es obra del arquitecto Ventura Rodr\u00edguez y sigue un estilo neocl\u00e1sico que combina algunos elementos barrocos. Tambi\u00e9n destacan unas magn\u00edficas vidrieras.<\/p>\n\n\n\n<p>Adem\u00e1s de los estudiantes,hab\u00edan otras personas con curiosidad por presenciar las disecciones,generalmente miembros de familias importantes.  Con tal de satisfacer este morbo,se habilit\u00f3 un espacio superior desde el que se pod\u00edan observar los trabajos a trav\u00e9s de una celos\u00eda.<\/p>\n\n\n\n<p>El antiguo Colegio de Cirug\u00eda se convirti\u00f3 en Facultad de Medicina en 1843,cuando se clausur\u00f3 la Universidad de Cervera. All\u00ed permaneci\u00f3 hasta que fue trasladada al Hospital Cl\u00ednic en 1907. El edificio,delante del Instituto de Estudios Catalanes,fue cedido a la Academia de Medicina en 1929,despu\u00e9s de haber sido la Escuela de Magisterio durante un cierto tiempo.<\/p>\n\n\n\n<p>El premio N\u00f3bel,Santiago Ram\u00f3n y Cajal,fue uno de los cient\u00edficos destacados que desarrollaron su actividad en el Colegio de Cirug\u00eda,durante su estancia en Barcelona entre 1887 y 1892.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El recinto del antiguo Hospital de la Santa Creu,en el Raval,guarda uno de los vestigios relacionados con la pr\u00e1ctica de la medicina en el siglo XVIII m\u00e1s desconocido y valioso,casi \u00fanico en Europa. Se trata del anfiteatro anat\u00f3mico construido en 1762 en la vieja sede del Colegio de Cirug\u00eda y que hoy alberga la Academia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-453","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=453"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/453\/revisions"}],"predecessor-version":[{"id":1338,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/453\/revisions\/1338"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}