{"id":222,"date":"2019-01-14T11:59:46","date_gmt":"2019-01-14T10:59:46","guid":{"rendered":"http:\/\/historiasdelahistoria.gruporomar.nl\/?p=222"},"modified":"2022-05-03T16:52:35","modified_gmt":"2022-05-03T16:52:35","slug":"un-paseo-por-la-historia-via-sepulcral-romana","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2019\/01\/14\/un-paseo-por-la-historia-via-sepulcral-romana\/","title":{"rendered":"UN PASEO POR LA HISTORIA: V\u00cdA SEPULCRAL ROMANA"},"content":{"rendered":"\n<p>Si paseamos por Las Ramblas de Barcelona nos podemos desviar por la calle Canuda hasta llegar a la plaza Vila de Madrid,donde encontraremos la V\u00eda Sepulcral Romana,con sus tumbas,un espacio funerario que estuvo en uso entre los siglos I al III d. C.<\/p>\n\n\n\n<p>Dejemos correr la imaginaci\u00f3n y transport\u00e9monos a un pasado no muy lejano&#8230;<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Este lugar estaba ocupado por el convento de Santa Teresa de las Carmelitas Descalzas desde 1588,donde viv\u00edan siete religiosas. A finales del siglo XIX vemos apresurado entre aquellas calles a un hombre con sotana,es Moss\u00e8n Jacint Verdaguer,que se dirige a la iglesia del convento a dar misa.<\/p>\n\n\n\n<p>Una vez terminada la Guerra Civil,el convento y los edificios afectados por los bombardeos son demolidos. Pero no es hasta 1954,cuando inician unas obras para construir viviendas,que se descubre la v\u00eda sepulcral romana.<\/p>\n\n\n\n<p>Si entramos en el recinto viajaremos a\u00fan m\u00e1s lejos&#8230;hasta los siglos I al III d. C. &#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/IMG_20190101_142416-2.jpg\" alt=\"\" class=\"wp-image-1029\" width=\"474\" height=\"598\"\/><figcaption>V\u00cdA SEPULCRAL. <br>FOTO: GLORIX.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ataviados con nuestra t\u00fanica romana y calzando unas sandalias,nos dirigimos a Barcino por el camino que entra por la puerta meridional de la muralla que da al cardo maximus de la ciudad. La sombra de los pinos,encinas y robles nos protegen del c\u00e1lido sol del verano.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/04\/vs.jpg\" alt=\"\" class=\"wp-image-1188\" width=\"468\" height=\"359\"\/><figcaption>FOTO: INTERNET<\/figcaption><\/figure><\/div>\n\n\n\n<p>Antes de entrar en la ciudad y atravesar el pomerium (era la frontera sagrada de la ciudad,la muralla&#8230;Barcino solo exist\u00eda dentro del pomerium,el resto eran solo las tierras adyacentes),encontramos la necr\u00f3polis y nos detenemos a leer los epitafios de las tumbas que se disponen a ambos lados del camino,junto a cultivos de cereales y vi\u00f1as. Epitafios que nos hablan de Pedanius Dionysius,y vemos a su esposa Fabia Ferriola llorando su muerte; a Flavia Chrysis hija de Terentia Fuscula depositando sobre la tumba de su madre unas rosas; a Trocina Eroticus despidi\u00e9ndose de su padre Eroticus y de su hermana Erotrice.<\/p>\n\n\n\n<p>Un poco m\u00e1s all\u00e1 unos padres lloran la p\u00e9rdida de su hijo peque\u00f1o,el cual dejar\u00e1n descansar para toda la eternidad en un \u00e1nfora.<\/p>\n\n\n\n<p>Dos transe\u00fantes pasan por nuestro lado y uno de ellos relata en voz baja como se enterr\u00f3 a un vecino dentro de un silo,atado de manos y sin el m\u00e1s m\u00ednimo respeto.<\/p>\n\n\n\n<p>Todos ellos gente sencilla y humilde. Unos han sido inhumados y otros incinerados,a veces all\u00ed mismo. Amigos y familiares hacen ofrendas florales y banquetes funerarios con ovejas,cabras,cerdos y bueyes y alguna vez sacrifican a alg\u00fan animal de compa\u00f1\u00eda como perros y aves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si paseamos por Las Ramblas de Barcelona nos podemos desviar por la calle Canuda hasta llegar a la plaza Vila de Madrid,donde encontraremos la V\u00eda Sepulcral Romana,con sus tumbas,un espacio funerario que estuvo en uso entre los siglos I al III d. C. Dejemos correr la imaginaci\u00f3n y transport\u00e9monos a un pasado no muy lejano&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-222","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/222\/revisions"}],"predecessor-version":[{"id":1401,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/222\/revisions\/1401"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}