{"id":1473,"date":"2022-05-22T10:37:08","date_gmt":"2022-05-22T10:37:08","guid":{"rendered":"http:\/\/historiasdelahistoria.rodmar.es\/?p=1473"},"modified":"2025-03-24T14:49:26","modified_gmt":"2025-03-24T14:49:26","slug":"la-plaza-pentadecagonal","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2022\/05\/22\/la-plaza-pentadecagonal\/","title":{"rendered":"LA PLAZA PENTADECAGONAL"},"content":{"rendered":"\n<p>Desde la primera ocasi\u00f3n que me llegaron noticias sobre la existencia de esta plaza, tuve la intenci\u00f3n de escribir, alg\u00fan d\u00eda, una entrada que hablase sobre ella. Estamos en el barrio G\u00f3tico y este espacio tan singular con forma geom\u00e9trica es la plaza de Milans. La admiraci\u00f3n aumenta cuando una se da cuenta que se trata de una plaza pentadecagonal, es decir, que forma un pol\u00edgono regular de 15 lados, una figura que se percibe en toda su plenitud cuando se alza la vista y el per\u00edmetro de la plaza se recorta en el cielo.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>La plaza Milans es de peque\u00f1as dimensiones y hace las funciones de v\u00e9rtice de la calle en \u00e1ngulo del mismo nombre que une las de Aviny\u00f3 y Cign\u00e0s. Su origen se remonta a mediados del siglo XIX, cuando la ciudad inici\u00f3 un nuevo urbanismo hacia la modernidad. La iniciativa coincidi\u00f3 con el derribo de las murallas y la liberaci\u00f3n de espacios en la ciudad antigua (ocupados principalmente por edificios religiosos) como consecuencia de la desamortizaci\u00f3n eclesi\u00e1stica.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG_20220521_193008.jpg\" alt=\"\" class=\"wp-image-1474\" width=\"345\" height=\"421\" srcset=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG_20220521_193008.jpg 429w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG_20220521_193008-246x300.jpg 246w\" sizes=\"(max-width: 345px) 100vw, 345px\" \/><figcaption>PLAZA MILANS.  FOTO: GLORIX.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Una generaci\u00f3n de arquitectos formados en la escuela de la Llotja e influidos por los ingenieros militares borb\u00f3nicos y las matem\u00e1ticas fueron los encargados de dar forma a esta nueva Barcelona. La prestigiosa Academia de Matem\u00e1ticas ejerci\u00f3 un papel esencial en este fen\u00f3meno. Instalada en el antiguo convento de St. Agust\u00edn, fue una escuela de ingenier\u00eda militar de referencia en toda Europa entre los siglos XVIII y XIX.<\/p>\n\n\n\n<p>Uno de estos nuevos arquitectos fue Francisco Daniel Molina, autor de la urbanizaci\u00f3n de la calle y la plaza de Milans, as\u00ed como de algunos de sus edificios. La plaza Real fue su gran obra en Barcelona, aunque tambi\u00e9n firm\u00f3 otros espacios emblem\u00e1ticos como la plaza del Duque de Medinaceli y la fuente del Genio Catal\u00e1n, en Pla del Palau. En 1855 fue nombrado arquitecto municipal, periodo en el que dise\u00f1\u00f3 el actual sal\u00f3n de plenos del ayuntamiento.<\/p>\n\n\n\n<p>La calle y la plaza de Milans son una clara muesta de la influencia de la cultura de las matem\u00e1ticas en este arquitecto y todo un homenaje a la geometr\u00eda. La urbanizaci\u00f3n de este espacio fue consecuencia, en este caso, no de la desamortizaci\u00f3n, sino del derribo, en 1856, del antiguo Palau Reial Menor, entonces en estado de ruina y que se erig\u00eda donde hac\u00eda siglos los templarios se hab\u00edan instalado.<\/p>\n\n\n\n<p>En esta curiosa v\u00eda, hoy reservada a los peatones, Molina concibi\u00f3 una peque\u00f1a plaza en el punto donde converg\u00edan los dos tramos de la calle en forma de \u00e1ngulo obtuso. Fue una manera ingeniosa de conseguir m\u00e1s luminosidad para los edificios, ya que las fachadas ganaban en amplitud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la primera ocasi\u00f3n que me llegaron noticias sobre la existencia de esta plaza, tuve la intenci\u00f3n de escribir, alg\u00fan d\u00eda, una entrada que hablase sobre ella. Estamos en el barrio G\u00f3tico y este espacio tan singular con forma geom\u00e9trica es la plaza de Milans. La admiraci\u00f3n aumenta cuando una se da cuenta que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1473","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/1473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=1473"}],"version-history":[{"count":2,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/1473\/revisions"}],"predecessor-version":[{"id":1477,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/1473\/revisions\/1477"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=1473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=1473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=1473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}