{"id":1466,"date":"2022-05-16T08:01:25","date_gmt":"2022-05-16T08:01:25","guid":{"rendered":"http:\/\/historiasdelahistoria.rodmar.es\/?p=1466"},"modified":"2025-03-24T14:49:26","modified_gmt":"2025-03-24T14:49:26","slug":"la-calle-mas-estrecha-de-barcelona","status":"publish","type":"post","link":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/2022\/05\/16\/la-calle-mas-estrecha-de-barcelona\/","title":{"rendered":"LA CALLE M\u00c1S ESTRECHA DE BARCELONA"},"content":{"rendered":"\n<p>Hoy toca de nuevo pasar por el barrio de La Ribera donde encontramos una peque\u00f1a calle, peque\u00f1a en tama\u00f1o pero no en historia. Situada detr\u00e1s de la Bas\u00edlica de Santa Mar\u00eda del Mar, entre la calle Montcada y la calle Flassader (en la que siglos atr\u00e1s se fabricaban mantas o frazadas), injustamente ignorada por los transe\u00fantes que por all\u00ed pasan, se encuentra la calle m\u00e1s estrecha de Barcelona, es la calle de las Moscas (Carrer de les Mosques).<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>S\u00ed, en ese barrio encontramos muchas calles peque\u00f1as y estrechas, y es que antes de derrumbar las murallas de Barcelona para ampliar la ciudad hab\u00eda m\u00e1s de 200 calles con un ancho inferior a los tres metros. La calle de las Moscas presenta tan solo 1,48 metros de pared a pared en su punto m\u00e1s estrecho, lo que la convierte en la m\u00e1s estrecha de la ciudad, sin contar a la ya desaparecida calle Doncelles, con 1,10 metros tras la reforma de la Via Laietana. La calle de las Moscas tambi\u00e9n se la conoc\u00eda popularmente como la calle de los crucificados, pues muchos al llegar a la calle extend\u00edan los brazos para tocar sus paredes.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG-20220512-WA0002.jpg\" alt=\"\" class=\"wp-image-1467\" width=\"332\" height=\"681\" srcset=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG-20220512-WA0002.jpg 998w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG-20220512-WA0002-146x300.jpg 146w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG-20220512-WA0002-499x1024.jpg 499w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG-20220512-WA0002-768x1576.jpg 768w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG-20220512-WA0002-749x1536.jpg 749w\" sizes=\"(max-width: 332px) 100vw, 332px\" \/><figcaption>CARRER DE LES MOSQUES. FOTO: GLORIX.<\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>\u00bfY por qu\u00e9 de las Moscas?<\/strong><\/p>\n\n\n\n<p>Moscas hab\u00edan y muchas en esa calle, y es que esos d\u00edpteros hac\u00edan sus delicias, sobretodo en verano, atra\u00eddas por el olor de las mercanc\u00edas que all\u00ed se acumulaban y que no se vend\u00edan en los cercanos mercados de Sta. Caterina, que abastec\u00eda al barrio desde 1845, y del Born. La falta de ventilaci\u00f3n de la calle debido a su estrechez ayudar\u00eda a que ese lugar se convirtiera en el para\u00edso terrenal de esos insectos voladores, pero tambi\u00e9n en un infierno para los vecinos que all\u00ed viv\u00edan.<\/p>\n\n\n\n<p><strong>\u00abAl carrer de les Mosques hi ha funci\u00f3 a les fosques\u00bb.<\/strong><\/p>\n\n\n\n<p>Este dicho catal\u00e1n vendr\u00eda a traducirse como \u00abEn la calle de las Moscas hay una funci\u00f3n en la oscuridad\u00bb, refiri\u00e9ndose a que en esta calle tambi\u00e9n se escond\u00eda un famoso burdel muy frecuentado por marineros, soldados y de las tropas extranjeras durante la guerra de Sucesi\u00f3n.<\/p>\n\n\n\n<p>Muestra p\u00e9trea de su existencia es la Carassa o cabeza de un se\u00f1or de piedra que encontramos en una esquina en la entrada de la calle, conocida como papamoscas por su similitud con el de la catedral de Burgos. Debemos recordar que entonces era frecuente se\u00f1alar la existencia de prost\u00edbulos pintando la casa con una l\u00ednea de color rojo, o con el n\u00famero de la casa algo m\u00e1s grande que el resto y en ocasiones con estas se\u00f1ales de piedra.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG_20220513_133052.jpg\" alt=\"\" class=\"wp-image-1468\" width=\"379\" height=\"387\" srcset=\"https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG_20220513_133052.jpg 310w, https:\/\/historiasdelahistoria.rodmar.es\/wp-content\/uploads\/2022\/05\/IMG_20220513_133052-293x300.jpg 293w\" sizes=\"(max-width: 379px) 100vw, 379px\" \/><figcaption>DETALLE DE LA CARASSA. FOTO: GLORIX<\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>La f\u00e1brica de monedas<\/strong><\/p>\n\n\n\n<p>Esta diminuta y en apariencia insignificante calle esconde otro secreto olvidado por el paso del tiempo. Durante el siglo XIII era all\u00ed donde se hac\u00eda moneda en la<strong> f\u00e1brica de la Seca<\/strong> (sekka en \u00e1rabe), que vendr\u00eda a significar \u00ablugar donde se fabrica moneda\u00bb.<\/p>\n\n\n\n<p>As\u00ed pues, la calle de las Moscas es sin lugar a dudas una calle singular de Barcelona, y tambi\u00e9n hay que decir que en lo que a peque\u00f1o se refiere, un SEAT 600 le super\u00f3 cuando en una ocasi\u00f3n consigui\u00f3 cruzarla gracias a su 1,38 metros de anchura&#8230;.a\u00fan le sobraron 10 cent\u00edmetros.<\/p>\n\n\n\n<p>Por cierto, en la actualidad, una reja impide el acceso desde hace algo m\u00e1s de dos d\u00e9cadas, impidiendo as\u00ed que siga utiliz\u00e1ndose de urinario p\u00fablico entre los inc\u00edvicos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy toca de nuevo pasar por el barrio de La Ribera donde encontramos una peque\u00f1a calle, peque\u00f1a en tama\u00f1o pero no en historia. Situada detr\u00e1s de la Bas\u00edlica de Santa Mar\u00eda del Mar, entre la calle Montcada y la calle Flassader (en la que siglos atr\u00e1s se fabricaban mantas o frazadas), injustamente ignorada por los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1466","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"_links":{"self":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/1466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/comments?post=1466"}],"version-history":[{"count":1,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/1466\/revisions"}],"predecessor-version":[{"id":1470,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/posts\/1466\/revisions\/1470"}],"wp:attachment":[{"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/media?parent=1466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/categories?post=1466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/historiasdelahistoria.rodmar.es\/index.php\/wp-json\/wp\/v2\/tags?post=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}